{"id":9878,"date":"2022-07-21T12:40:56","date_gmt":"2022-07-21T17:40:56","guid":{"rendered":"https:\/\/kardo.org\/?post_type=product&#038;p=9878"},"modified":"2023-10-17T00:36:37","modified_gmt":"2023-10-17T05:36:37","slug":"wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres","status":"publish","type":"product","link":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/","title":{"rendered":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)"},"content":{"rendered":"<p>Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n, basado en Proverbios 31 grandioso estudio para madres de hijos peque\u00f1os. Este es un excelente recurso para l\u00edderes. Proporciona a la l\u00edder de informaci\u00f3n \u00fatil sobre la forma de planificar, organizar y dirigir un grupo de estudio de la Biblia con el libro de estudio. Nota: Puedes comprar esta Gu\u00eda del L\u00edder individual o como parte del paquete de muestra.<\/p>\n<p>NOTA: Esta opci\u00f3n en l\u00ednea est\u00e1 siempre disponible para usted una vez comprado y es interactivo con rellenar los espacios en blanco que se puede editar y actualizar a medida que aprender y crecer.\u00a0 \u00a0Usted recibir\u00e1 un correo electr\u00f3nico de Kardo con el enlace al estudio en l\u00ednea y las instrucciones para el acceso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,  [&#8230;]<\/p>\n","protected":false},"featured_media":10774,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false},"product_brand":[],"product_cat":[113,26],"product_tag":[],"class_list":["post-9878","product","type-product","status-publish","has-post-thumbnail","product_cat-online-bible-studies","product_cat-spanish","product_shipping_class-online","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"zh_CN\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Kardo Ministries - Strengthening Families\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries\" \/>\n\t\t<meta property=\"og:description\" content=\"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-07-21T17:40:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-17T05:36:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kardo.org\\\/zh\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kardo.org\\\/zh\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/#listItem\",\"name\":\"Translations\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/#listItem\",\"position\":3,\"name\":\"Translations\",\"item\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/spanish\\\/#listItem\",\"name\":\"Spanish\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/spanish\\\/#listItem\",\"position\":4,\"name\":\"Spanish\",\"item\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/spanish\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#listItem\",\"name\":\"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/#listItem\",\"name\":\"Translations\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#listItem\",\"position\":5,\"name\":\"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product-category\\\/translations\\\/spanish\\\/#listItem\",\"name\":\"Spanish\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#itempage\",\"url\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/\",\"name\":\"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries\",\"description\":\"Es un estudio de diez semanas que te ayudar\\u00e1n a encontrar respuestas b\\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\\u00e1s del estudio b\\u00edblico aprender\\u00e1s a mejorar tus habilidades maternas y encontrar\\u00e1s Consejo pr\\u00e1ctico para mam\\u00e1 dise\\u00f1ado para las mam\\u00e1s de todas las edades al finalizar cada lecci\\u00f3n,\",\"inLanguage\":\"zh-CN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/kardo.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/E-bookSpanishWFM.png?fit=896%2C571&ssl=1\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#mainImage\",\"width\":896,\"height\":571},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/product\\\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\\\/#mainImage\"},\"datePublished\":\"2022-07-21T12:40:56-05:00\",\"dateModified\":\"2023-10-17T00:36:37-05:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/#organization\",\"name\":\"Kardo Ministries\",\"description\":\"Strengthening Families\",\"url\":\"https:\\\/\\\/kardo.org\\\/zh\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/kardo.org\\\/zh\\\/\",\"name\":\"Kardo Ministries\",\"description\":\"Strengthening Families\",\"inLanguage\":\"zh-CN\",\"publisher\":{\"@id\":\"https:\\\/\\\/kardo.org\\\/zh\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries","description":"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,","canonical_url":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh#listItem","position":1,"name":"Home","item":"https:\/\/kardo.org\/zh","nextItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/kardo.org\/zh\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/#listItem","name":"Translations"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/#listItem","position":3,"name":"Translations","item":"https:\/\/kardo.org\/zh\/product-category\/translations\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/#listItem","name":"Spanish"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/#listItem","position":4,"name":"Spanish","item":"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/","nextItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#listItem","name":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/#listItem","name":"Translations"}},{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#listItem","position":5,"name":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)","previousItem":{"@type":"ListItem","@id":"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/#listItem","name":"Spanish"}}]},{"@type":"ItemPage","@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#itempage","url":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/","name":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries","description":"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,","inLanguage":"zh-CN","isPartOf":{"@id":"https:\/\/kardo.org\/zh\/#website"},"breadcrumb":{"@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/kardo.org\/wp-content\/uploads\/2022\/07\/E-bookSpanishWFM.png?fit=896%2C571&ssl=1","@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#mainImage","width":896,"height":571},"primaryImageOfPage":{"@id":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/#mainImage"},"datePublished":"2022-07-21T12:40:56-05:00","dateModified":"2023-10-17T00:36:37-05:00"},{"@type":"Organization","@id":"https:\/\/kardo.org\/zh\/#organization","name":"Kardo Ministries","description":"Strengthening Families","url":"https:\/\/kardo.org\/zh\/"},{"@type":"WebSite","@id":"https:\/\/kardo.org\/zh\/#website","url":"https:\/\/kardo.org\/zh\/","name":"Kardo Ministries","description":"Strengthening Families","inLanguage":"zh-CN","publisher":{"@id":"https:\/\/kardo.org\/zh\/#organization"}}]},"og:locale":"zh_CN","og:site_name":"Kardo Ministries - Strengthening Families","og:type":"article","og:title":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries","og:description":"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,","og:url":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/","article:published_time":"2022-07-21T17:40:56+00:00","article:modified_time":"2023-10-17T05:36:37+00:00","twitter:card":"summary_large_image","twitter:title":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres) - Kardo Ministries","twitter:description":"Es un estudio de diez semanas que te ayudar\u00e1n a encontrar respuestas b\u00edblicas a preguntas importantes acerca de tu matrimonio, cuidado de los hijos y tus prioridades. Adem\u00e1s del estudio b\u00edblico aprender\u00e1s a mejorar tus habilidades maternas y encontrar\u00e1s Consejo pr\u00e1ctico para mam\u00e1 dise\u00f1ado para las mam\u00e1s de todas las edades al finalizar cada lecci\u00f3n,"},"aioseo_meta_data":{"post_id":"9878","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-20 17:35:27","updated":"2025-11-06 01:45:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kardo.org\/zh\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kardo.org\/zh\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kardo.org\/zh\/product-category\/translations\/\" title=\"Translations\">Translations<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/\" title=\"Spanish\">Spanish<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/kardo.org\/zh"},{"label":"Shop","link":"https:\/\/kardo.org\/zh\/shop\/"},{"label":"Translations","link":"https:\/\/kardo.org\/zh\/product-category\/translations\/"},{"label":"Spanish","link":"https:\/\/kardo.org\/zh\/product-category\/translations\/spanish\/"},{"label":"Wisdom for Mothers (Spanish) ONLINE Bible Study (Sabiduria Para Madres)","link":"https:\/\/kardo.org\/zh\/product\/wisdom-for-mothers-spanish-online-bible-study-sabiduria-para-madres\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/product\/9878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/media\/10774"}],"wp:attachment":[{"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/media?parent=9878"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/product_brand?post=9878"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/product_cat?post=9878"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kardo.org\/zh\/wp-json\/wp\/v2\/product_tag?post=9878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}